{"id":27405,"date":"2021-12-31T21:11:11","date_gmt":"2022-01-01T00:11:11","guid":{"rendered":"https:\/\/quebrandocontrole.com.br\/site\/?p=27405"},"modified":"2021-12-31T21:11:22","modified_gmt":"2022-01-01T00:11:22","slug":"um-feliz-2022-para-todos","status":"publish","type":"post","link":"https:\/\/quebrandocontrole.com.br\/site\/um-feliz-2022-para-todos\/","title":{"rendered":"Um Feliz 2022 para todos!"},"content":{"rendered":"\n<p><a href=\"https:\/\/www.instagram.com\/ucegamers\/\" target=\"_blank\" rel=\"noopener\">ucegamers<\/a>\u00a0E &#8220;zeramos&#8221; mais um ano. Superado com muitos desafios, e claro com aqueles &#8220;BOSS&#8221; que todos temos nos nossos dias, mas depois de 12 fazes conclu\u00edmos mais um game, e esperamos que a nova DLC possa vir com novos desafios, mais aprendizado e muita divers\u00e3o.<\/p>\n\n\n\n<p><br>Feliz Ano Novo a Todos!<br><a href=\"https:\/\/www.instagram.com\/explore\/tags\/unidossomosgamers\/\" target=\"_blank\" rel=\"noopener\">#UnidosSomosGamers<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ucegamers\u00a0E &#8220;zeramos&#8221; mais um ano. Superado com muitos desafios, e claro com aqueles &#8220;BOSS&#8221; que todos temos nos nossos dias, mas depois de 12 fazes conclu\u00edmos mais um game, e esperamos que a nova DLC possa vir com novos desafios, mais aprendizado e muita divers\u00e3o. Feliz Ano Novo a Todos!#UnidosSomosGamers<\/p>\n","protected":false},"author":66,"featured_media":27406,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[178,1],"tags":[],"class_list":["post-27405","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","category-uncategorized"],"wpmagazine_modules_lite_featured_media_urls":{"thumbnail":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2021\/12\/270292230_638976644188937_582030971637030139_n-150x150.jpg",150,150,true],"cvmm-medium":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2021\/12\/270292230_638976644188937_582030971637030139_n.jpg",300,300,false],"cvmm-medium-plus":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2021\/12\/270292230_638976644188937_582030971637030139_n.jpg",207,207,false],"cvmm-portrait":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2021\/12\/270292230_638976644188937_582030971637030139_n.jpg",400,400,false],"cvmm-medium-square":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2021\/12\/270292230_638976644188937_582030971637030139_n.jpg",600,600,false],"cvmm-large":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2021\/12\/270292230_638976644188937_582030971637030139_n.jpg",640,640,false],"cvmm-small":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2021\/12\/270292230_638976644188937_582030971637030139_n.jpg",95,95,false],"full":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2021\/12\/270292230_638976644188937_582030971637030139_n.jpg",640,640,false]},"categories_names":{"178":{"name":"Artigos","link":"https:\/\/quebrandocontrole.com.br\/site\/category\/artigos\/"},"1":{"name":"Uncategorized","link":"https:\/\/quebrandocontrole.com.br\/site\/category\/uncategorized\/"}},"tags_names":[],"comments_number":"0","_links":{"self":[{"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/posts\/27405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/users\/66"}],"replies":[{"embeddable":true,"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/comments?post=27405"}],"version-history":[{"count":0,"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/posts\/27405\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/media\/27406"}],"wp:attachment":[{"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/media?parent=27405"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/categories?post=27405"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/tags?post=27405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}