{"id":37679,"date":"2023-02-14T23:04:47","date_gmt":"2023-02-15T02:04:47","guid":{"rendered":"https:\/\/quebrandocontrole.com.br\/site\/?p=37679"},"modified":"2023-02-14T23:04:48","modified_gmt":"2023-02-15T02:04:48","slug":"fas-fazem-dublagem-espetacular-para-filme-de-super-mario-que-nunca-foi-lancado-no-brasil","status":"publish","type":"post","link":"https:\/\/quebrandocontrole.com.br\/site\/fas-fazem-dublagem-espetacular-para-filme-de-super-mario-que-nunca-foi-lancado-no-brasil\/","title":{"rendered":"F\u00e3s fazem dublagem espetacular para filme de Super Mario que nunca foi lan\u00e7ado no Brasil."},"content":{"rendered":"\n<p>Foto :\u00a0Melanya Fiaux<\/p>\n\n\n\n<p>Em dezembro do ano passado, a comunidade nintendista surpreendeu a todos com uma \u00f3tima not\u00edcia. <\/p>\n\n\n\n<p>O filme &#8220;Super Mario Bros.: P\u012bchi-hime Kyushutsu Dai Sakusen!&#8221; (1986), lan\u00e7ado apenas nos cinemas japoneses, recebeu uma dublagem feita por f\u00e3s liderada pelo canal Maxel Thu Thu.<\/p>\n\n\n\n<p>O projeto contou com dubladores como Nintendo Fan, Mori\u00e1 Velis, Alexsandro Magalh\u00e3es e outros f\u00e3s, demonstrando o interesse em difundir o conte\u00fado da Nintendo para o p\u00fablico brasileiro, e at\u00e9 mesmo contou com a participa\u00e7\u00e3o de dubladores profissionais, como Melanya Fiaux.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\"  id=\"_ytid_93398\"  width=\"640\" height=\"480\"  data-origwidth=\"640\" data-origheight=\"480\" src=\"https:\/\/www.youtube.com\/embed\/77l3ccGBAc8?enablejsapi=1&#038;autoplay=0&#038;cc_load_policy=0&#038;cc_lang_pref=&#038;iv_load_policy=1&#038;loop=0&#038;rel=1&#038;fs=1&#038;playsinline=0&#038;autohide=2&#038;theme=dark&#038;color=red&#038;controls=1&#038;disablekb=0&#038;\" class=\"__youtube_prefs__  epyt-is-override  no-lazyload\" title=\"YouTube player\"  allow=\"fullscreen; accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Foto :\u00a0Melanya Fiaux Em dezembro do ano passado, a comunidade nintendista surpreendeu a todos com uma \u00f3tima not\u00edcia. O filme &#8220;Super Mario Bros.: P\u012bchi-hime Kyushutsu Dai Sakusen!&#8221; (1986), lan\u00e7ado apenas nos cinemas japoneses, recebeu uma dublagem feita por f\u00e3s liderada pelo canal Maxel Thu Thu. O projeto contou com dubladores como Nintendo Fan, Mori\u00e1 Velis, [&hellip;]<\/p>\n","protected":false},"author":66,"featured_media":37680,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[8,6],"tags":[],"class_list":["post-37679","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-ultimas-noticias"],"wpmagazine_modules_lite_featured_media_urls":{"thumbnail":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2023\/02\/Batsugun-Rating-Korea_02-03-23-768x432-1-4-150x150.jpg",150,150,true],"cvmm-medium":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2023\/02\/Batsugun-Rating-Korea_02-03-23-768x432-1-4.jpg",300,300,false],"cvmm-medium-plus":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2023\/02\/Batsugun-Rating-Korea_02-03-23-768x432-1-4.jpg",206,207,false],"cvmm-portrait":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2023\/02\/Batsugun-Rating-Korea_02-03-23-768x432-1-4.jpg",400,402,false],"cvmm-medium-square":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2023\/02\/Batsugun-Rating-Korea_02-03-23-768x432-1-4.jpg",597,600,false],"cvmm-large":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2023\/02\/Batsugun-Rating-Korea_02-03-23-768x432-1-4.jpg",1019,1024,false],"cvmm-small":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2023\/02\/Batsugun-Rating-Korea_02-03-23-768x432-1-4.jpg",95,95,false],"full":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2023\/02\/Batsugun-Rating-Korea_02-03-23-768x432-1-4.jpg",1447,1454,false]},"categories_names":{"8":{"name":"Not\u00edcias","link":"https:\/\/quebrandocontrole.com.br\/site\/category\/noticias\/"},"6":{"name":"\u00daltimas not\u00edcias","link":"https:\/\/quebrandocontrole.com.br\/site\/category\/noticias\/ultimas-noticias\/"}},"tags_names":[],"comments_number":"0","_links":{"self":[{"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/posts\/37679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/users\/66"}],"replies":[{"embeddable":true,"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/comments?post=37679"}],"version-history":[{"count":0,"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/posts\/37679\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/media\/37680"}],"wp:attachment":[{"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/media?parent=37679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/categories?post=37679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/tags?post=37679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}