{"id":40379,"date":"2023-04-26T23:46:20","date_gmt":"2023-04-27T02:46:20","guid":{"rendered":"https:\/\/quebrandocontrole.com.br\/site\/?p=40379"},"modified":"2023-04-26T23:46:21","modified_gmt":"2023-04-27T02:46:21","slug":"pdp-anuncia-novos-acessorios-de-zelda-para-nintendo-switch","status":"publish","type":"post","link":"https:\/\/quebrandocontrole.com.br\/site\/pdp-anuncia-novos-acessorios-de-zelda-para-nintendo-switch\/","title":{"rendered":"PDP anuncia novos acess\u00f3rios de Zelda para Nintendo Switch."},"content":{"rendered":"\n<p>Foto :&nbsp;Nintenderos<\/p>\n\n\n\n<p>Faltam apenas algumas semanas para o t\u00e3o esperado lan\u00e7amento de The Legend of Zelda: Tears of the Kingdom. E parece que as empresas de acess\u00f3rios est\u00e3o muito atentas a isso.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\">Zelda: L\u00e1grimas do Reino<\/h6>\n\n\n\n<p>Ap\u00f3s o an\u00fancio em seu trailer final, a PDP anunciou dois novos produtos com tem\u00e1tica de Zelda. S\u00e3o eles:<\/p>\n\n\n\n<p>Um controle Pro com tema Sheikah por US$ 28 que brilha no escuro, oferece \u00e1udio no jogo e capacidade de bate-papo USB. Voc\u00ea pode verificar sua disponibilidade aqui.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Foto :&nbsp;Nintenderos<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Ele tamb\u00e9m anunciou um estojo de viagem com tema Sheikah que brilha no escuro, compat\u00edvel com o Switch, Switch Lite e OLED Switch. O estojo pode ser adquirido por US$ 20 e voc\u00ea pode verificar a disponibilidade aqui.<\/p>\n\n\n\n<p>The Legend of Zelda: Tears of the Kingdom ser\u00e1 lan\u00e7ado em 12 de maio de 2023 e que h\u00e1 brindes exclusivos para quem fizer a pr\u00e9-venda do jogo\u00a0\u00a0com alguns\u00a0<a href=\"https:\/\/www.nintenderos.com\/?s=zelda+regalo\">presentes para reserv\u00e1-lo<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foto :&nbsp;Nintenderos Faltam apenas algumas semanas para o t\u00e3o esperado lan\u00e7amento de The Legend of Zelda: Tears of the Kingdom. E parece que as empresas de acess\u00f3rios est\u00e3o muito atentas a isso. Zelda: L\u00e1grimas do Reino Ap\u00f3s o an\u00fancio em seu trailer final, a PDP anunciou dois novos produtos com tem\u00e1tica de Zelda. S\u00e3o eles: [&hellip;]<\/p>\n","protected":false},"author":66,"featured_media":40380,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-40379","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"wpmagazine_modules_lite_featured_media_urls":{"thumbnail":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2023\/04\/mando-zelda-pdp-150x150.webp",150,150,true],"cvmm-medium":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2023\/04\/mando-zelda-pdp.webp",300,171,false],"cvmm-medium-plus":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2023\/04\/mando-zelda-pdp.webp",305,173,false],"cvmm-portrait":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2023\/04\/mando-zelda-pdp.webp",400,227,false],"cvmm-medium-square":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2023\/04\/mando-zelda-pdp.webp",600,341,false],"cvmm-large":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2023\/04\/mando-zelda-pdp.webp",790,449,false],"cvmm-small":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2023\/04\/mando-zelda-pdp.webp",130,74,false],"full":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2023\/04\/mando-zelda-pdp.webp",790,449,false]},"categories_names":{"1":{"name":"Uncategorized","link":"https:\/\/quebrandocontrole.com.br\/site\/category\/uncategorized\/"}},"tags_names":[],"comments_number":"0","_links":{"self":[{"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/posts\/40379","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/users\/66"}],"replies":[{"embeddable":true,"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/comments?post=40379"}],"version-history":[{"count":0,"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/posts\/40379\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/media\/40380"}],"wp:attachment":[{"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/media?parent=40379"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/categories?post=40379"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/tags?post=40379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}