{"id":43225,"date":"2023-09-03T21:59:24","date_gmt":"2023-09-04T00:59:24","guid":{"rendered":"https:\/\/quebrandocontrole.com.br\/site\/?p=43225"},"modified":"2023-09-03T21:59:26","modified_gmt":"2023-09-04T00:59:26","slug":"conheca-a-geladeira-gamer-da-heineken-que-resfria-a-cerveja-e-o-pc","status":"publish","type":"post","link":"https:\/\/quebrandocontrole.com.br\/site\/conheca-a-geladeira-gamer-da-heineken-que-resfria-a-cerveja-e-o-pc\/","title":{"rendered":"Conhe\u00e7a a geladeira gamer da Heineken que resfria a cerveja e o PC."},"content":{"rendered":"\n<p>Foto :&nbsp;Heineken<\/p>\n\n\n\n<p>A Heineken, conhecida mundialmente por suas cervejas, decidiu entrar no universo gamer de uma maneira inusitada.<\/p>\n\n\n\n<p>Para comemorar o Dia Internacional do Gamer que aconteceu nesta ter\u00e7a-feira (29 de agosto de 2023), a empresa revelou ao mundo o The Gaming Fridge, um dispositivo que combina uma CPU com geladeira e que promete resfriar o seu PC e ainda manter a cervejinha gelada.<\/p>\n\n\n\n<p>A iniciativa faz parte da campanha \u201cNem toda rodada \u00e9 l\u00e1 fora\u201d, que visa destacar a intera\u00e7\u00e3o social no universo dos jogos, desmistificando a ideia de que os gamers n\u00e3o s\u00e3o soci\u00e1veis.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\"  id=\"_ytid_23642\"  width=\"640\" height=\"360\"  data-origwidth=\"640\" data-origheight=\"360\" src=\"https:\/\/www.youtube.com\/embed\/q0ZPQaK_rxc?enablejsapi=1&#038;autoplay=0&#038;cc_load_policy=0&#038;cc_lang_pref=&#038;iv_load_policy=1&#038;loop=0&#038;rel=1&#038;fs=1&#038;playsinline=0&#038;autohide=2&#038;theme=dark&#038;color=red&#038;controls=1&#038;disablekb=0&#038;\" class=\"__youtube_prefs__  epyt-is-override  no-lazyload\" title=\"YouTube player\"  allow=\"fullscreen; accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Desenvolvido em parceria com as equipes da Le Pub S\u00e3o Paulo e Le Pub Mil\u00e3o, com a colabora\u00e7\u00e3o da LeGarage e produ\u00e7\u00e3o da Monogrid, o projeto promete oferecer uma experi\u00eancia diferenciada aos usu\u00e1rios.<\/p>\n\n\n\n<p>gor de Castro, gerente s\u00eanior de marketing da Heineken 0.0 no Brasil, mostrou-se animado com a novidade, enfatizando como ela une o mundo dos jogos e os momentos de socializa\u00e7\u00e3o, tornando-os ainda mais prazerosos. J\u00e1 Felipe Cury, CCO de Le Pub S\u00e3o Paulo, destacou a dedica\u00e7\u00e3o da empresa em enriquecer encontros sociais, apontando a relev\u00e2ncia da geladeira gamer para a comunidade, tornando-os mais agrad\u00e1veis e descontra\u00eddos.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Como adquirir a The Gaming Fridge?<\/strong><\/h4>\n\n\n\n<p><img decoding=\"async\" src=\"https:\/\/img.ibxk.com.br\/2023\/08\/30\/30130303998177.jpg?ims=328x\" alt=\"\">Foto:\u00a0\u00a0Heineken\u00a0<\/p>\n\n\n\n<p>Para aqueles interessados em ter essa inova\u00e7\u00e3o em casa, a Heineken anunciou que realizar\u00e1 um sorteio. Mais detalhes sobre a promo\u00e7\u00e3o ser\u00e3o divulgados em breve. No entanto, ainda n\u00e3o h\u00e1 informa\u00e7\u00f5es sobre a data de lan\u00e7amento do produto para venda ao p\u00fablico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foto :&nbsp;Heineken A Heineken, conhecida mundialmente por suas cervejas, decidiu entrar no universo gamer de uma maneira inusitada. Para comemorar o Dia Internacional do Gamer que aconteceu nesta ter\u00e7a-feira (29 de agosto de 2023), a empresa revelou ao mundo o The Gaming Fridge, um dispositivo que combina uma CPU com geladeira e que promete resfriar [&hellip;]<\/p>\n","protected":false},"author":66,"featured_media":43227,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[8,6],"tags":[],"class_list":["post-43225","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-ultimas-noticias"],"wpmagazine_modules_lite_featured_media_urls":{"thumbnail":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2023\/09\/Roxx-Energy-Street-Fighter-6-2-150x150.webp",150,150,true],"cvmm-medium":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2023\/09\/Roxx-Energy-Street-Fighter-6-2.webp",300,113,false],"cvmm-medium-plus":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2023\/09\/Roxx-Energy-Street-Fighter-6-2.webp",305,114,false],"cvmm-portrait":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2023\/09\/Roxx-Energy-Street-Fighter-6-2.webp",400,150,false],"cvmm-medium-square":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2023\/09\/Roxx-Energy-Street-Fighter-6-2.webp",600,225,false],"cvmm-large":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2023\/09\/Roxx-Energy-Street-Fighter-6-2.webp",704,264,false],"cvmm-small":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2023\/09\/Roxx-Energy-Street-Fighter-6-2.webp",130,49,false],"full":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2023\/09\/Roxx-Energy-Street-Fighter-6-2.webp",704,264,false]},"categories_names":{"8":{"name":"Not\u00edcias","link":"https:\/\/quebrandocontrole.com.br\/site\/category\/noticias\/"},"6":{"name":"\u00daltimas not\u00edcias","link":"https:\/\/quebrandocontrole.com.br\/site\/category\/noticias\/ultimas-noticias\/"}},"tags_names":[],"comments_number":"0","_links":{"self":[{"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/posts\/43225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/users\/66"}],"replies":[{"embeddable":true,"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/comments?post=43225"}],"version-history":[{"count":0,"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/posts\/43225\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/media\/43227"}],"wp:attachment":[{"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/media?parent=43225"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/categories?post=43225"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/tags?post=43225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}