{"id":44110,"date":"2023-10-08T22:51:01","date_gmt":"2023-10-09T01:51:01","guid":{"rendered":"https:\/\/quebrandocontrole.com.br\/site\/?p=44110"},"modified":"2023-10-08T22:51:02","modified_gmt":"2023-10-09T01:51:02","slug":"netflix-anuncia-segunda-temporada-de-castlevania-nocturne","status":"publish","type":"post","link":"https:\/\/quebrandocontrole.com.br\/site\/netflix-anuncia-segunda-temporada-de-castlevania-nocturne\/","title":{"rendered":"Netflix anuncia segunda temporada de Castlevania: Nocturne."},"content":{"rendered":"\n<p>Foto :&nbsp;Netflix<\/p>\n\n\n\n<p>Parece que &#8220;Castlevania: Nocturne&#8221; \u00e9 um spin-off da s\u00e9rie animada &#8220;Castlevania&#8221; originalmente lan\u00e7ada em 2017 e que a primeira temporada foi bem recebida pelo p\u00fablico. \u00c9 \u00f3timo saber que a Netflix anunciou a renova\u00e7\u00e3o da s\u00e9rie para uma segunda temporada. Os f\u00e3s com certeza est\u00e3o animados com essa not\u00edcia.<\/p>\n\n\n\n<p>\u00c9 comum que as s\u00e9ries de sucesso sejam renovadas para temporadas adicionais, e \u00e9 bom ver que &#8220;Castlevania: Nocturne&#8221; continuar\u00e1 a explorar o universo da franquia &#8220;Castlevania&#8221;. Esperamos ansiosamente por mais informa\u00e7\u00f5es sobre a segunda temporada \u00e0 medida que a produ\u00e7\u00e3o avan\u00e7a.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Confira:<\/h5>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-incorporar-manipulador wp-block-embed-incorporar-manipulador wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Castlevania: Nocturne | Season 2 Official Announcement | Netflix\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/04SvzaCxULw?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Parece que esta s\u00e9rie expande o universo da franquia &#8220;Castlevania&#8221; ao focar na hist\u00f3ria de origem de Richter Belmont e situ\u00e1-la durante a revolu\u00e7\u00e3o francesa. Isso oferece uma perspectiva \u00fanica e emocionante para os f\u00e3s da s\u00e9rie.<\/p>\n\n\n\n<p>A narrativa de amor e perda, bem como o ambiente g\u00f3tico e a presen\u00e7a de vampiros, s\u00e3o elementos ic\u00f4nicos da franquia &#8220;Castlevania&#8221; que certamente continuar\u00e3o a atrair os espectadores. \u00c9 bom saber que a s\u00e9rie est\u00e1 nas m\u00e3os de profissionais talentosos como o showrunner Kevin Kolde e o criador\/roteirista Clive Bradley.<\/p>\n\n\n\n<p>F\u00e3s de &#8220;Castlevania&#8221; e amantes de anima\u00e7\u00e3o t\u00eam muito o que esperar com essa nova s\u00e9rie.<\/p>\n\n\n\n<p>Obrigado por compartilhar essas informa\u00e7\u00f5es e destacar a disponibilidade da primeira temporada na Netflix para que os interessados possam assisti-la.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foto :&nbsp;Netflix Parece que &#8220;Castlevania: Nocturne&#8221; \u00e9 um spin-off da s\u00e9rie animada &#8220;Castlevania&#8221; originalmente lan\u00e7ada em 2017 e que a primeira temporada foi bem recebida pelo p\u00fablico. \u00c9 \u00f3timo saber que a Netflix anunciou a renova\u00e7\u00e3o da s\u00e9rie para uma segunda temporada. Os f\u00e3s com certeza est\u00e3o animados com essa not\u00edcia. \u00c9 comum que as [&hellip;]<\/p>\n","protected":false},"author":66,"featured_media":44112,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[8,6],"tags":[],"class_list":["post-44110","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-ultimas-noticias"],"wpmagazine_modules_lite_featured_media_urls":{"thumbnail":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2023\/10\/FB_IMG_1696219224588-150x150.jpg",150,150,true],"cvmm-medium":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2023\/10\/FB_IMG_1696219224588.jpg",300,225,false],"cvmm-medium-plus":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2023\/10\/FB_IMG_1696219224588.jpg",276,207,false],"cvmm-portrait":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2023\/10\/FB_IMG_1696219224588.jpg",400,300,false],"cvmm-medium-square":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2023\/10\/FB_IMG_1696219224588.jpg",480,360,false],"cvmm-large":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2023\/10\/FB_IMG_1696219224588.jpg",480,360,false],"cvmm-small":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2023\/10\/FB_IMG_1696219224588.jpg",127,95,false],"full":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2023\/10\/FB_IMG_1696219224588.jpg",480,360,false]},"categories_names":{"8":{"name":"Not\u00edcias","link":"https:\/\/quebrandocontrole.com.br\/site\/category\/noticias\/"},"6":{"name":"\u00daltimas not\u00edcias","link":"https:\/\/quebrandocontrole.com.br\/site\/category\/noticias\/ultimas-noticias\/"}},"tags_names":[],"comments_number":"0","_links":{"self":[{"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/posts\/44110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/users\/66"}],"replies":[{"embeddable":true,"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/comments?post=44110"}],"version-history":[{"count":0,"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/posts\/44110\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/media\/44112"}],"wp:attachment":[{"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/media?parent=44110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/categories?post=44110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/tags?post=44110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}