{"id":46848,"date":"2024-01-01T16:51:24","date_gmt":"2024-01-01T19:51:24","guid":{"rendered":"https:\/\/quebrandocontrole.com.br\/site\/?p=46848"},"modified":"2024-01-01T16:51:25","modified_gmt":"2024-01-01T19:51:25","slug":"gran-turismo-inspirado-em-game-da-sony-estreia-na-hbo-max","status":"publish","type":"post","link":"https:\/\/quebrandocontrole.com.br\/site\/gran-turismo-inspirado-em-game-da-sony-estreia-na-hbo-max\/","title":{"rendered":"Gran Turismo, inspirado em game da Sony, estreia na HBO Max"},"content":{"rendered":"\n<p>O filme Gran Turismo, que tem produ\u00e7\u00e3o e roteiro baseados em game hom\u00f4nimo da Sony, acaba de chegar \u00e0 plataforma de estreaming de v\u00eddeos HBO Max.<\/p>\n\n\n\n<p>A produ\u00e7\u00e3o \u00e9 assinada pelo diretor Neill Blomkamp, respons\u00e1vel por longas como Distrito 9 e Elysium, com roteiro de Jason Hall e Zach Baylin.<\/p>\n\n\n\n<p>A ideia \u00e9 parcialmente inspirada na vida de Jann Mardenborough, um jogador de Gran Turismo que migrou das corridas virtuais para as disputas automobil\u00edsticas, tornando-se piloto profissional.<\/p>\n\n\n\n<p>Gran Turismo \u00e9 uma franquia de games de corrida desenvolvida pelo Polyphony Digital, est\u00fadio japon\u00eas pertencente \u00e0 Sony, que conta com jogos para o PlayStation desde 1997.<\/p>\n\n\n\n<p>Para assistir, \u00e9 necess\u00e1rio assinatura do servi\u00e7o de streaming <a href=\"https:\/\/www.hbomax.com\/br\/pt\/feature\/urn:hbo:feature:GZUq0cQyP8LqspgEAABdm\" data-type=\"URL\" data-id=\"https:\/\/www.hbomax.com\/br\/pt\/feature\/urn:hbo:feature:GZUq0cQyP8LqspgEAABdm\" target=\"_blank\" rel=\"noreferrer noopener\">HBO Max<\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\"  id=\"_ytid_10512\"  width=\"640\" height=\"360\"  data-origwidth=\"640\" data-origheight=\"360\" src=\"https:\/\/www.youtube.com\/embed\/W2oXkCFH-cE?enablejsapi=1&#038;autoplay=0&#038;cc_load_policy=0&#038;cc_lang_pref=&#038;iv_load_policy=1&#038;loop=0&#038;rel=1&#038;fs=1&#038;playsinline=0&#038;autohide=2&#038;theme=dark&#038;color=red&#038;controls=1&#038;disablekb=0&#038;\" class=\"__youtube_prefs__  epyt-is-override  no-lazyload\" title=\"YouTube player\"  allow=\"fullscreen; accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Fonte: <a href=\"https:\/\/www.jbox.com.br\/2024\/01\/01\/gran-turismo-estreia-na-hbo-max\/\" data-type=\"URL\" data-id=\"https:\/\/www.jbox.com.br\/2024\/01\/01\/gran-turismo-estreia-na-hbo-max\/\" target=\"_blank\" rel=\"noreferrer noopener\">JBox<\/a><\/p>\n\n\n\n<p>Imagem: Sony Pictures Brasil<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para assistir, \u00e9 necess\u00e1rio assinatura do servi\u00e7o de streaming de v\u00eddeo.<\/p>\n","protected":false},"author":76,"featured_media":46849,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[8,6],"tags":[865,1338,1337,1335,1336,1339,417,1340,218],"class_list":["post-46848","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-ultimas-noticias","tag-game-2","tag-game-cine","tag-gran-turismo","tag-hbo","tag-hbo-max","tag-jogos-de-corrida","tag-playstation","tag-racing-game","tag-sony"],"wpmagazine_modules_lite_featured_media_urls":{"thumbnail":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2024\/01\/Gran-Turismo-Filme-150x150.jpg",150,150,true],"cvmm-medium":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2024\/01\/Gran-Turismo-Filme-300x300.jpg",300,300,true],"cvmm-medium-plus":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2024\/01\/Gran-Turismo-Filme-305x207.jpg",305,207,true],"cvmm-portrait":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2024\/01\/Gran-Turismo-Filme-400x600.jpg",400,600,true],"cvmm-medium-square":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2024\/01\/Gran-Turismo-Filme-600x600.jpg",600,600,true],"cvmm-large":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2024\/01\/Gran-Turismo-Filme-1024x614.jpg",1024,614,true],"cvmm-small":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2024\/01\/Gran-Turismo-Filme-130x95.jpg",130,95,true],"full":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2024\/01\/Gran-Turismo-Filme.jpg",1064,614,false]},"categories_names":{"8":{"name":"Not\u00edcias","link":"https:\/\/quebrandocontrole.com.br\/site\/category\/noticias\/"},"6":{"name":"\u00daltimas not\u00edcias","link":"https:\/\/quebrandocontrole.com.br\/site\/category\/noticias\/ultimas-noticias\/"}},"tags_names":{"865":{"name":"Game","link":"https:\/\/quebrandocontrole.com.br\/site\/tag\/game-2\/"},"1338":{"name":"Game Cine","link":"https:\/\/quebrandocontrole.com.br\/site\/tag\/game-cine\/"},"1337":{"name":"Gran Turismo","link":"https:\/\/quebrandocontrole.com.br\/site\/tag\/gran-turismo\/"},"1335":{"name":"HBO","link":"https:\/\/quebrandocontrole.com.br\/site\/tag\/hbo\/"},"1336":{"name":"HBO Max","link":"https:\/\/quebrandocontrole.com.br\/site\/tag\/hbo-max\/"},"1339":{"name":"Jogos de Corrida","link":"https:\/\/quebrandocontrole.com.br\/site\/tag\/jogos-de-corrida\/"},"417":{"name":"PlayStation","link":"https:\/\/quebrandocontrole.com.br\/site\/tag\/playstation\/"},"1340":{"name":"Racing Game","link":"https:\/\/quebrandocontrole.com.br\/site\/tag\/racing-game\/"},"218":{"name":"Sony","link":"https:\/\/quebrandocontrole.com.br\/site\/tag\/sony\/"}},"comments_number":"0","_links":{"self":[{"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/posts\/46848","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/users\/76"}],"replies":[{"embeddable":true,"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/comments?post=46848"}],"version-history":[{"count":0,"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/posts\/46848\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/media\/46849"}],"wp:attachment":[{"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/media?parent=46848"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/categories?post=46848"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/tags?post=46848"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}