{"id":50198,"date":"2024-05-24T09:34:16","date_gmt":"2024-05-24T12:34:16","guid":{"rendered":"https:\/\/quebrandocontrole.com.br\/site\/?p=50198"},"modified":"2024-05-24T09:34:50","modified_gmt":"2024-05-24T12:34:50","slug":"atari-anuncia-a-aquisicao-da-marca-intellivision-sua-antiga-rival","status":"publish","type":"post","link":"https:\/\/quebrandocontrole.com.br\/site\/atari-anuncia-a-aquisicao-da-marca-intellivision-sua-antiga-rival\/","title":{"rendered":"Atari anuncia a aquisi\u00e7\u00e3o da marca Intellivision, sua antiga rival"},"content":{"rendered":"\n<p>Com as aquisi\u00e7\u00f5es frequentes na ind\u00fastria de jogos, recentemente, n\u00e3o surpreende a movimenta\u00e7\u00e3o da Atari, que anunciou essa semana a aquisi\u00e7\u00e3o de sua antiga rival nos tempos dos primeiros consoles, a Intellivision.<\/p>\n\n\n\n<p>A empresa adquiriu a marca Intellivision e seu cat\u00e1logo de 200 jogos da Intellivision Entertainment. Como parte do acordo, a desenvolvedora adquirida reformular\u00e1 a marca e continuar\u00e1 produzindo e distribuindo o console de jogos Amico, em desenvolvimento h\u00e1 alguns e ainda n\u00e3o lan\u00e7ado, e trabalhar\u00e1 com a licen\u00e7a da Atari para distribuir novas vers\u00f5es dos jogos cl\u00e1ssicos no console.<\/p>\n\n\n\n<p>\u201cEsta foi uma oportunidade \u00fanica de unir antigos concorrentes e reunir os f\u00e3s da Atari, Intellivision e da era de ouro dos jogos\u201d, disse o presidente e CEO da Atari, Wade Rosen, em comunicado \u00e0 imprensa, afirmando que a Atari buscar\u00e1 expandir a distribui\u00e7\u00e3o digital e f\u00edsica dos jogos da Intellivision, explorando oportunidades de licenciamento.<\/p>\n\n\n\n<p>\u201cConsideramos a Atari um parceiro valioso e temos plena confian\u00e7a de que ser\u00e3o administradores respons\u00e1veis da famosa marca Intellivision\u201d, acrescentou o CEO da Intellivision Entertainment, Phil Adam. \u201cEsperamos expandir nossa colabora\u00e7\u00e3o e trazer uma ampla gama de novos t\u00edtulos Atari e Intellivision para as plataformas de jogos da fam\u00edlia Amico e Amico Home.\u201d<\/p>\n\n\n\n<p>A Atari tem reconquistado a aten\u00e7\u00e3o do p\u00fablico, com aquisi\u00e7\u00f5es recentes, como o Nightdive Studios e Digital Eclipse, publicando tamb\u00e9m jogos como Mr. Run and Jump e Atari 50: The Anniversary Celebration, bem recebidos no mercado.<\/p>\n\n\n\n<p>Fontes : <a href=\"https:\/\/www-gameinformer-com.translate.goog\/2024\/05\/23\/atari-announces-intellivision-brand-acquisition?_x_tr_sl=auto&amp;_x_tr_tl=en&amp;_x_tr_hl=pt-BR\" target=\"_blank\" rel=\"noopener\">Game Informer<\/a><\/p>\n\n\n\n<p>Imagens : Game Informer<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Atari tem reconquistado a aten\u00e7\u00e3o do p\u00fablico, com aquisi\u00e7\u00f5es recentes.<\/p>\n","protected":false},"author":66,"featured_media":50199,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[8,6],"tags":[],"class_list":["post-50198","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-ultimas-noticias"],"wpmagazine_modules_lite_featured_media_urls":{"thumbnail":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2024\/05\/4300226-nintendoworldchampionshipsjapan-150x150.jpg",150,150,true],"cvmm-medium":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2024\/05\/4300226-nintendoworldchampionshipsjapan-300x300.jpg",300,300,true],"cvmm-medium-plus":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2024\/05\/4300226-nintendoworldchampionshipsjapan-305x207.jpg",305,207,true],"cvmm-portrait":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2024\/05\/4300226-nintendoworldchampionshipsjapan-400x600.jpg",400,600,true],"cvmm-medium-square":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2024\/05\/4300226-nintendoworldchampionshipsjapan-600x600.jpg",600,600,true],"cvmm-large":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2024\/05\/4300226-nintendoworldchampionshipsjapan-1024x821.jpg",1024,821,true],"cvmm-small":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2024\/05\/4300226-nintendoworldchampionshipsjapan-130x95.jpg",130,95,true],"full":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2024\/05\/4300226-nintendoworldchampionshipsjapan.jpg",1460,821,false]},"categories_names":{"8":{"name":"Not\u00edcias","link":"https:\/\/quebrandocontrole.com.br\/site\/category\/noticias\/"},"6":{"name":"\u00daltimas not\u00edcias","link":"https:\/\/quebrandocontrole.com.br\/site\/category\/noticias\/ultimas-noticias\/"}},"tags_names":[],"comments_number":"0","_links":{"self":[{"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/posts\/50198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/users\/66"}],"replies":[{"embeddable":true,"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/comments?post=50198"}],"version-history":[{"count":0,"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/posts\/50198\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/media\/50199"}],"wp:attachment":[{"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/media?parent=50198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/categories?post=50198"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/tags?post=50198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}