{"id":52621,"date":"2024-10-28T10:45:53","date_gmt":"2024-10-28T13:45:53","guid":{"rendered":"https:\/\/quebrandocontrole.com.br\/site\/?p=52621"},"modified":"2024-10-28T10:45:53","modified_gmt":"2024-10-28T13:45:53","slug":"hq-brasileira-dungeoneers-apresenta-aventureiros-em-trama-classica-de-rpg","status":"publish","type":"post","link":"https:\/\/quebrandocontrole.com.br\/site\/hq-brasileira-dungeoneers-apresenta-aventureiros-em-trama-classica-de-rpg\/","title":{"rendered":"HQ brasileira Dungeoneers apresenta aventureiros em trama cl\u00e1ssica de RPG"},"content":{"rendered":"\n<p>Marcio Fiorito, um dos grandes nomes dos quadrinhos brasileiros da atualidade, levou seu mais recente projeto, a HQ Dungeoneers, para campanha de financiamento coletivo.<\/p>\n\n\n\n<p>A obra se inspira na narrativa de campanhas de RPG do pr\u00f3prio autor, f\u00e3 confesso do cl\u00e1ssico RPG Dungeons &amp; Dragons e jogador ass\u00edduo, seja como um personagem-jogador ou como o condutor da trama, na condi\u00e7\u00e3o de Dungeon Master.<\/p>\n\n\n\n<p>Escrita e desenhada pelo artista, com letras de Deyvison Manes, conhecido por Justi\u00e7a Sideral, e cor da capa por Renato Spiller, Dungeoneers #1 d\u00e1 sequ\u00eancia \u00e0 edi\u00e7\u00e3o piloto lan\u00e7ada em 2022 na CCXP, que inseria o grupo de aventureiros em situa\u00e7\u00f5es vividas por qualquer jogador de RPG, com direito a monstros e masmorras.<\/p>\n\n\n\n<p>A edi\u00e7\u00e3o n\u00famero &#8220;zero&#8221; contava com somente nove p\u00e1ginas, nas quais os aventureiros saem como explores de ru\u00ednas em busca do artefato Orbe das Vis\u00f5es. As coisas, como previsto, saem do controle, gerando um divertido ponto de partida, que ter\u00e1 sequ\u00eancia com o novo projeto.<\/p>\n\n\n\n<p>A cria\u00e7\u00e3o contar\u00e1 novamente com a trupe de amigos, Brock, Kaycee, Melkir e Irm\u00e3 Lyria, que precisam aceitar uma tarefa ap\u00f3s uma miss\u00e3o fracassada. A miss\u00e3o, teoricamente simples, ganhou mais desdobramentos, mudando n\u00e3o apenas o destino deles, mas o destino de todo o mundo.<\/p>\n\n\n\n<p>Dungeoneers #1 ter\u00e1 32 p\u00e1ginas e as artes caprichadas do ilustrador, previstas originalmente em preto e branco, mas que ganharam cores e uma extens\u00e3o da revista para 40 p\u00e1ginas, com artes originais de profissionais convidados, ap\u00f3s o alcance das metas adicionais do <a href=\"https:\/\/www.catarse.me\/dungeoneers\" data-type=\"link\" data-id=\"https:\/\/www.catarse.me\/dungeoneers\" target=\"_blank\" rel=\"noreferrer noopener\">financiamento no Catarse<\/a>, que j\u00e1 atingiu 164% do total determinado, at\u00e9 o momento.<\/p>\n\n\n\n<p>O lan\u00e7amento oficial de Dungeoneers #1 acontecer\u00e1 no Artist&#8217;s Valley da CCXP, evento de cultura Geek que se realiza esse ano entre os dias 05 a 08 de dezembro 2024.<\/p>\n\n\n\n<div class=\"wp-block-jetpack-slideshow aligncenter\" data-effect=\"slide\"><div class=\"wp-block-jetpack-slideshow_container swiper-container\"><ul class=\"wp-block-jetpack-slideshow_swiper-wrapper swiper-wrapper\"><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"681\" height=\"1024\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-52623\" data-id=\"52623\" src=\"https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2024\/10\/Dungeoneers1-681x1024.jpg\" srcset=\"https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2024\/10\/Dungeoneers1-681x1024.jpg 681w, https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2024\/10\/Dungeoneers1-200x300.jpg 200w, https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2024\/10\/Dungeoneers1-768x1155.jpg 768w, https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2024\/10\/Dungeoneers1-1021x1536.jpg 1021w, https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2024\/10\/Dungeoneers1-400x600.jpg 400w, https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2024\/10\/Dungeoneers1.jpg 1064w\" sizes=\"auto, (max-width: 681px) 100vw, 681px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"664\" height=\"1024\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-52624\" data-id=\"52624\" src=\"https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2024\/10\/Dungeoneers2-664x1024.jpg\" srcset=\"https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2024\/10\/Dungeoneers2-664x1024.jpg 664w, https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2024\/10\/Dungeoneers2-195x300.jpg 195w, https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2024\/10\/Dungeoneers2-768x1184.jpg 768w, https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2024\/10\/Dungeoneers2-996x1536.jpg 996w, https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2024\/10\/Dungeoneers2.jpg 1038w\" sizes=\"auto, (max-width: 664px) 100vw, 664px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"664\" height=\"1024\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-52625\" data-id=\"52625\" src=\"https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2024\/10\/Dungeoneers3-664x1024.jpg\" srcset=\"https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2024\/10\/Dungeoneers3-664x1024.jpg 664w, https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2024\/10\/Dungeoneers3-195x300.jpg 195w, https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2024\/10\/Dungeoneers3-768x1184.jpg 768w, https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2024\/10\/Dungeoneers3-996x1536.jpg 996w, https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2024\/10\/Dungeoneers3.jpg 1038w\" sizes=\"auto, (max-width: 664px) 100vw, 664px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"664\" height=\"1024\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-52626\" data-id=\"52626\" src=\"https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2024\/10\/Dungeoneers4-664x1024.jpg\" srcset=\"https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2024\/10\/Dungeoneers4-664x1024.jpg 664w, https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2024\/10\/Dungeoneers4-195x300.jpg 195w, https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2024\/10\/Dungeoneers4-768x1184.jpg 768w, https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2024\/10\/Dungeoneers4-996x1536.jpg 996w, https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2024\/10\/Dungeoneers4.jpg 1038w\" sizes=\"auto, (max-width: 664px) 100vw, 664px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"664\" height=\"1024\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-52627\" data-id=\"52627\" src=\"https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2024\/10\/Dungeoneers5-664x1024.jpg\" srcset=\"https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2024\/10\/Dungeoneers5-664x1024.jpg 664w, https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2024\/10\/Dungeoneers5-195x300.jpg 195w, https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2024\/10\/Dungeoneers5-768x1184.jpg 768w, https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2024\/10\/Dungeoneers5-996x1536.jpg 996w, https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2024\/10\/Dungeoneers5.jpg 1038w\" sizes=\"auto, (max-width: 664px) 100vw, 664px\" \/><\/figure><\/li><\/ul><a class=\"wp-block-jetpack-slideshow_button-prev swiper-button-prev swiper-button-white\" role=\"button\"><\/a><a class=\"wp-block-jetpack-slideshow_button-next swiper-button-next swiper-button-white\" role=\"button\"><\/a><a aria-label=\"Pause Slideshow\" class=\"wp-block-jetpack-slideshow_button-pause\" role=\"button\"><\/a><div class=\"wp-block-jetpack-slideshow_pagination swiper-pagination swiper-pagination-white\"><\/div><\/div><\/div>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\"  id=\"_ytid_93339\"  width=\"640\" height=\"360\"  data-origwidth=\"640\" data-origheight=\"360\" src=\"https:\/\/www.youtube.com\/embed\/PbujXeyiHfE?enablejsapi=1&#038;autoplay=0&#038;cc_load_policy=0&#038;cc_lang_pref=&#038;iv_load_policy=1&#038;loop=0&#038;rel=1&#038;fs=1&#038;playsinline=0&#038;autohide=2&#038;theme=dark&#038;color=red&#038;controls=1&#038;disablekb=0&#038;\" class=\"__youtube_prefs__  epyt-is-override  no-lazyload\" title=\"YouTube player\"  allow=\"fullscreen; accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Fonte: <a href=\"https:\/\/obarquinhocultural.com\/2024\/10\/25\/dungeoneers-traz-uma-aventura-fantastica-baseada-no-jogo-de-rpg\" data-type=\"link\" data-id=\"https:\/\/obarquinhocultural.com\/2024\/10\/25\/dungeoneers-traz-uma-aventura-fantastica-baseada-no-jogo-de-rpg\" target=\"_blank\" rel=\"noreferrer noopener\">O Barquinho Cultural<\/a><\/p>\n\n\n\n<p>Imagem: reprodu\u00e7\u00e3o<\/p>\n","protected":false},"excerpt":{"rendered":"<p>HQ ser\u00e1 lan\u00e7ada na CCXP 2024.<\/p>\n","protected":false},"author":76,"featured_media":52622,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1247,1251,8,6],"tags":[944,871,803,2864,160],"class_list":["post-52621","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura_geek","category-livros","category-noticias","category-ultimas-noticias","tag-ccxp-2","tag-cultura-geek","tag-dungeons-dragons","tag-hq-brasileira","tag-rpg"],"wpmagazine_modules_lite_featured_media_urls":{"thumbnail":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2024\/10\/Dungeoneers-n.1-150x150.webp",150,150,true],"cvmm-medium":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2024\/10\/Dungeoneers-n.1-300x300.webp",300,300,true],"cvmm-medium-plus":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2024\/10\/Dungeoneers-n.1-305x207.webp",305,207,true],"cvmm-portrait":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2024\/10\/Dungeoneers-n.1-400x600.webp",400,600,true],"cvmm-medium-square":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2024\/10\/Dungeoneers-n.1-600x600.webp",600,600,true],"cvmm-large":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2024\/10\/Dungeoneers-n.1-1024x761.webp",1024,761,true],"cvmm-small":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2024\/10\/Dungeoneers-n.1-130x95.webp",130,95,true],"full":["https:\/\/quebrandocontrole.com.br\/site\/wp-content\/uploads\/2024\/10\/Dungeoneers-n.1.webp",1436,761,false]},"categories_names":{"1247":{"name":"Cultura Geek","link":"https:\/\/quebrandocontrole.com.br\/site\/category\/cultura_geek\/"},"1251":{"name":"Livros","link":"https:\/\/quebrandocontrole.com.br\/site\/category\/cultura_geek\/livros\/"},"8":{"name":"Not\u00edcias","link":"https:\/\/quebrandocontrole.com.br\/site\/category\/noticias\/"},"6":{"name":"\u00daltimas not\u00edcias","link":"https:\/\/quebrandocontrole.com.br\/site\/category\/noticias\/ultimas-noticias\/"}},"tags_names":{"944":{"name":"CCXP","link":"https:\/\/quebrandocontrole.com.br\/site\/tag\/ccxp-2\/"},"871":{"name":"Cultura Geek","link":"https:\/\/quebrandocontrole.com.br\/site\/tag\/cultura-geek\/"},"803":{"name":"Dungeons &amp; Dragons","link":"https:\/\/quebrandocontrole.com.br\/site\/tag\/dungeons-dragons\/"},"2864":{"name":"HQ Brasileira","link":"https:\/\/quebrandocontrole.com.br\/site\/tag\/hq-brasileira\/"},"160":{"name":"rpg","link":"https:\/\/quebrandocontrole.com.br\/site\/tag\/rpg\/"}},"comments_number":"0","_links":{"self":[{"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/posts\/52621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/users\/76"}],"replies":[{"embeddable":true,"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/comments?post=52621"}],"version-history":[{"count":0,"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/posts\/52621\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/media\/52622"}],"wp:attachment":[{"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/media?parent=52621"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/categories?post=52621"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quebrandocontrole.com.br\/site\/wp-json\/wp\/v2\/tags?post=52621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}